{"id":1388,"date":"2018-06-18T16:54:17","date_gmt":"2018-06-18T14:54:17","guid":{"rendered":"http:\/\/localhost\/dermapp.ch\/page-daccueil\/"},"modified":"2025-07-17T15:14:21","modified_gmt":"2025-07-17T13:14:21","slug":"page-daccueil","status":"publish","type":"page","link":"https:\/\/dermapp.ch\/de\/","title":{"rendered":"Page d&#8217;accueil"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1325,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-1388","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>DermApp - Konsultieren Sie einen Dermatologen online f\u00fcr 59.- CHF<\/title>\n<meta name=\"description\" content=\"Online-Konsultation mit zertifizierten Dermatologen in Ihrer N\u00e4he. Sie k\u00f6nnen Ihnen helfen, Ihr Hautproblem zu l\u00f6sen, w\u00e4hrend Sie zu Hause bleiben.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dermapp.ch\/de\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DermApp - Konsultieren Sie einen Dermatologen online f\u00fcr 59.- CHF\" \/>\n<meta property=\"og:description\" content=\"Online-Konsultation mit zertifizierten Dermatologen in Ihrer N\u00e4he. Sie k\u00f6nnen Ihnen helfen, Ihr Hautproblem zu l\u00f6sen, w\u00e4hrend Sie zu Hause bleiben.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dermapp.ch\/de\/\" \/>\n<meta property=\"og:site_name\" content=\"Dermapp\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-17T13:14:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/staging.dermapp.ch\/app\/uploads\/2018\/06\/medecins.png\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dermapp.ch\/de\/\",\"url\":\"https:\/\/dermapp.ch\/de\/\",\"name\":\"DermApp - Konsultieren Sie einen Dermatologen online f\u00fcr 59.- CHF\",\"isPartOf\":{\"@id\":\"https:\/\/dermapp.ch\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dermapp.ch\/de\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dermapp.ch\/de\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dermapp.ch\/app\/uploads\/2018\/08\/dermapp.jpg\",\"datePublished\":\"2018-06-18T14:54:17+00:00\",\"dateModified\":\"2025-07-17T13:14:21+00:00\",\"description\":\"Online-Konsultation mit zertifizierten Dermatologen in Ihrer N\u00e4he. Sie k\u00f6nnen Ihnen helfen, Ihr Hautproblem zu l\u00f6sen, w\u00e4hrend Sie zu Hause bleiben.\",\"breadcrumb\":{\"@id\":\"https:\/\/dermapp.ch\/de\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dermapp.ch\/de\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/dermapp.ch\/de\/#primaryimage\",\"url\":\"https:\/\/dermapp.ch\/app\/uploads\/2018\/08\/dermapp.jpg\",\"contentUrl\":\"https:\/\/dermapp.ch\/app\/uploads\/2018\/08\/dermapp.jpg\",\"width\":456,\"height\":526},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dermapp.ch\/de\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/staging.dermapp.ch\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Page d&rsquo;accueil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dermapp.ch\/de\/#website\",\"url\":\"https:\/\/dermapp.ch\/de\/\",\"name\":\"Dermapp\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dermapp.ch\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DermApp - Konsultieren Sie einen Dermatologen online f\u00fcr 59.- CHF","description":"Online-Konsultation mit zertifizierten Dermatologen in Ihrer N\u00e4he. Sie k\u00f6nnen Ihnen helfen, Ihr Hautproblem zu l\u00f6sen, w\u00e4hrend Sie zu Hause bleiben.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dermapp.ch\/de\/","og_locale":"de_DE","og_type":"article","og_title":"DermApp - Konsultieren Sie einen Dermatologen online f\u00fcr 59.- CHF","og_description":"Online-Konsultation mit zertifizierten Dermatologen in Ihrer N\u00e4he. Sie k\u00f6nnen Ihnen helfen, Ihr Hautproblem zu l\u00f6sen, w\u00e4hrend Sie zu Hause bleiben.","og_url":"https:\/\/dermapp.ch\/de\/","og_site_name":"Dermapp","article_modified_time":"2025-07-17T13:14:21+00:00","twitter_card":"summary_large_image","twitter_image":"https:\/\/staging.dermapp.ch\/app\/uploads\/2018\/06\/medecins.png","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dermapp.ch\/de\/","url":"https:\/\/dermapp.ch\/de\/","name":"DermApp - Konsultieren Sie einen Dermatologen online f\u00fcr 59.- CHF","isPartOf":{"@id":"https:\/\/dermapp.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dermapp.ch\/de\/#primaryimage"},"image":{"@id":"https:\/\/dermapp.ch\/de\/#primaryimage"},"thumbnailUrl":"https:\/\/dermapp.ch\/app\/uploads\/2018\/08\/dermapp.jpg","datePublished":"2018-06-18T14:54:17+00:00","dateModified":"2025-07-17T13:14:21+00:00","description":"Online-Konsultation mit zertifizierten Dermatologen in Ihrer N\u00e4he. Sie k\u00f6nnen Ihnen helfen, Ihr Hautproblem zu l\u00f6sen, w\u00e4hrend Sie zu Hause bleiben.","breadcrumb":{"@id":"https:\/\/dermapp.ch\/de\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dermapp.ch\/de\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/dermapp.ch\/de\/#primaryimage","url":"https:\/\/dermapp.ch\/app\/uploads\/2018\/08\/dermapp.jpg","contentUrl":"https:\/\/dermapp.ch\/app\/uploads\/2018\/08\/dermapp.jpg","width":456,"height":526},{"@type":"BreadcrumbList","@id":"https:\/\/dermapp.ch\/de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/staging.dermapp.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Page d&rsquo;accueil"}]},{"@type":"WebSite","@id":"https:\/\/dermapp.ch\/de\/#website","url":"https:\/\/dermapp.ch\/de\/","name":"Dermapp","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dermapp.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"}]}},"_links":{"self":[{"href":"https:\/\/dermapp.ch\/de\/wp-json\/wp\/v2\/pages\/1388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dermapp.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dermapp.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dermapp.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dermapp.ch\/de\/wp-json\/wp\/v2\/comments?post=1388"}],"version-history":[{"count":13,"href":"https:\/\/dermapp.ch\/de\/wp-json\/wp\/v2\/pages\/1388\/revisions"}],"predecessor-version":[{"id":3033,"href":"https:\/\/dermapp.ch\/de\/wp-json\/wp\/v2\/pages\/1388\/revisions\/3033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dermapp.ch\/de\/wp-json\/wp\/v2\/media\/1325"}],"wp:attachment":[{"href":"https:\/\/dermapp.ch\/de\/wp-json\/wp\/v2\/media?parent=1388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}